{"id":21599,"date":"2022-10-19T09:00:37","date_gmt":"2022-10-19T07:00:37","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=21599"},"modified":"2025-09-30T13:32:08","modified_gmt":"2025-09-30T11:32:08","slug":"sekretaer-sekretaerin","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/","title":{"rendered":"Sekret\u00e4rin: Aufgaben, Weiterbildungen &#038; Gehalt"},"content":{"rendered":"<p>Eine Sekret\u00e4rin \u00fcbernimmt administrative Aufgaben im Sekretariat, f\u00fchrt das Front-Office, regelt <strong>Telefon- und E-Mail-Verkehr<\/strong> und verwaltet Termine. Heute kann es unter Umst\u00e4nden auch sein, dass eine Sekret\u00e4rin andere Mitarbeiter brieft und <strong>Pr\u00e4sentations- oder sogar F\u00fchrungsaufgaben<\/strong> \u00fcbernimmt.<\/p>\n<h2><span lang=\"DE-AT\">Sekret\u00e4rin: Key Facts<\/span><\/h2>\n<div class=\"scroll-shadow\">\n<div class=\"scroll-shadow__shadow scroll-shadow__shadow--left\"><\/div>\n<div class=\"scroll-shadow__shadow scroll-shadow__shadow--right\"><\/div>\n<div class=\"scroll-shadow__content\">\n<table class=\"table table-facts\" style=\"width: 100%; margin-bottom: 40px;\">\n<tbody>\n<tr>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Ausbildung.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Ausbildung<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>Kauffrau f\u00fcr B\u00fcrokommunikation<\/li>\n<li>B\u00fcromanagement<\/li>\n<li>gepr\u00fcfte Office-Managerin<\/li>\n<\/ul>\n<\/td>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Hard-Skills.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Hard Skills<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>EDV-Kenntnisse, Microsoft Office<\/li>\n<li>Sprachenkenntnisse<\/li>\n<li>Branchenkenntnisse<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Weiterbildung.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Weiterbildung<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>Office-Management 4.0, erweitertes Management, Unternehmensorganisation und Kommunikation, agiles Office-Management u. v. m.<\/li>\n<\/ul>\n<\/td>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Soft-Skills.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Soft Skills<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>Organisationsst\u00e4rke<\/li>\n<li>Diplomatisches Geschick<\/li>\n<li>Kommunikationsf\u00e4higkeiten<\/li>\n<li>Zeitmanagement<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Gehalt.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Gehalt<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>von 27.000 bis 46.000 Euro brutto pro Jahr<\/li>\n<\/ul>\n<\/td>\n<td style=\"vertical-align: middle; text-align: center; padding: 0; min-width: 90px;\"><img decoding=\"async\" src=\"\/blog\/wp-content\/plugins\/seminartipp\/svgs\/Verwandte-Berufe.svg\" width=\"50px\" height=\"50px\" \/><\/td>\n<td style=\"padding: 15px 20px;\">\n<div style=\"font-size: 16px; font-weight: 600; margin-bottom: 5px;\">Verwandte Berufe<\/div>\n<ul class=\"inner-text-seminartipp\">\n<li>Assistenz der Gesch\u00e4ftsf\u00fchrung<\/li>\n<li>Office Manager<\/li>\n<li>B\u00fcrokaufmann<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<h2>Was ist eine Sekret\u00e4rin? Definition<\/h2>\n<p>Eine Sekret\u00e4rin ist h\u00e4ufig <strong>die erste Person, mit der Kunden in Kontakt kommen<\/strong>. Anrufe, Anfragen, Besuche und anderes finden zuerst im Sekretariat statt, bevor diese selektiert zum Chef kommen. Die Sekret\u00e4rin \u00fcbernimmt zudem die Kommunikation und den Schriftverkehr, <strong>organisiert B\u00fcroabl\u00e4ufe<\/strong> und bildet die Schnittstelle zwischen Kunden, Lieferanten, Mitarbeitern und der F\u00fchrungskraft.<\/p>\n<p>Die <a href=\"https:\/\/www.haufe-akademie.de\/hierarchy\/assistenz+und+office-management\">Ausbildung zur Sekret\u00e4rin<\/a> bereitet darauf vor, den heutzutage weitl\u00e4ufigen Aufgaben im Business gewachsen zu sein \u2013 denn der Sekret\u00e4r-Beruf hat sich einem enormen Wandel unterzogen. So zeichnet sich die Arbeit im Office zu einem gro\u00dfen Teil durch <strong>digitale Vernetzung<\/strong> aus. Zu den administrativen Aufgaben im Sekretariat geh\u00f6rt heute die Handhabung von firmeninternen Chat-Programmen, die <strong>Organisation von Terminen \u00fcber Video-Calls<\/strong> sowie andere Dinge, die fr\u00fcher nicht im Repertoire einer Sekret\u00e4rin zu finden waren.<\/p>\n<p>Es wird deutlich: Die klassische Bezeichnung der Sekret\u00e4rin mit klar definierten Aufgaben gibt es heute nicht mehr, denn die Aufgabenbereiche variieren von Firma zu Firma. Das zeigen z.B. die <strong>vielen Bezeichnungen f\u00fcr den Sekret\u00e4r-Beruf<\/strong>, beispielsweise:<\/p>\n<ul>\n<li>Vorstandsassistenz oder pers\u00f6nliche Assistenz<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8738\">Assistenz der Gesch\u00e4ftsf\u00fchrung<\/a><\/li>\n<li>(Chef-)Sekret\u00e4rin<\/li>\n<li>Executive Assistant oder Management Assistant<\/li>\n<li>Office Managerin<\/li>\n<\/ul>\n<p>Eine Aussage, die dennoch gemeinsam f\u00fcr alle Sekretariat-Aufgaben genannt werden kann, ist, dass die Hauptaufgabe einer Sekret\u00e4rin darin besteht, die <strong>F\u00fchrungskr\u00e4fte zu unterst\u00fctzen und zu entlasten<\/strong>.<\/p>\n<blockquote><p><strong>Tipp<\/strong><\/p>\n<p>Da die Aufgabenbereiche einer Sekret\u00e4rin so vielf\u00e4ltig sind, lohnt es sich auch, sinnvolle Grundlagenkurse f\u00fcr diesen Beruf zu absolvieren \u2013 z.B. Office-Management und Software- oder Social-Media-Kenntnisse. Spezialisieren kann man sich auch mit einer Basisbildung in bestimmten Bereichen (z.B. Datenschutz).<\/p><\/blockquote>\n<h2>Was macht eine Sekret\u00e4rin? Aufgaben<\/h2>\n<p>Die oben genannten Begriffe werden der <strong>Aufgabenvielfalt bei der Arbeit im Sekretariat<\/strong> viel eher gerecht als die mit veralteten Vorstellungen verbundene Bezeichnung \u201eSekret\u00e4rin\u201c. Denn im Zuge der Digitalisierung und <strong>immer neuen Management-Ans\u00e4tzen<\/strong> (z.B. <a href=\"https:\/\/www.haufe-akademie.de\/5396\">Agile Management<\/a>) sind laufend neue F\u00e4higkeiten gefragt. Neben administrativen Aufgaben im Sekretariat, die mit Genauigkeit und oft auch Koordinationsverm\u00f6gen erledigt werden m\u00fcssen, gilt es auch <strong>folgende Sekretariatsaufgaben<\/strong> zu erledigen:<\/p>\n<ul>\n<li>Telefonate (eingehend und ausgehend)<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8579\">Zeitmanagement<\/a>: Terminvergabe und -koordination<\/li>\n<li>Bearbeitung und Verwaltung ein- und ausgehender Post<\/li>\n<li>Gesch\u00e4ftliche Korrespondenzen regeln<\/li>\n<li>Nutzung von Office-Programmen (Word, Excel etc.)<\/li>\n<li>Dokumente erstellen<\/li>\n<li>Organisation: Ablagen- und Aktenmanagement, Datenbankpflege<\/li>\n<li>Protokollf\u00fchrung bei Meetings, Konferenzen und Veranstaltungen<\/li>\n<li>Reportings und <a href=\"https:\/\/www.haufe-akademie.de\/8715\">Pr\u00e4sentationen erstellen<\/a><\/li>\n<li>Kostenabrechnungen<\/li>\n<li>Organisation von Veranstaltungen, Gesch\u00e4ftsreisen oder Gesch\u00e4ftsessen<\/li>\n<\/ul>\n<p>Diese Liste der Aufgaben einer Sekret\u00e4rin l\u00e4sst sich\u00a0<strong>je nach Unternehmen und Branche<\/strong> erweitern. Beispielsweise kann es sein, dass in einem Unternehmen, das viel Online-Marketing betreibt, ein <a href=\"https:\/\/www.haufe-akademie.de\/5362\">Monitoring digitaler KPIs<\/a> gefragt ist oder gelegentlich der <a href=\"https:\/\/www.haufe-akademie.de\/31290\">Social-Media-Auftritt<\/a> verwaltet werden soll. <strong>T\u00e4tigkeiten einer Sekret\u00e4rin unterliegen einem steten Wandel<\/strong>.<\/p>\n<div class=\"seminartipp\">\r\n\t\r\n\t<div class=\"content-wrapper\">\r\n\t\t\r\n\t\t\t<div class=\"image\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"133\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt.jpg\" class=\"attachment-pod size-pod\" alt=\"\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt.jpg 680w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt-150x130@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt-150x130.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt-110x96.jpg 110w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2025\/02\/seminartipp-frau-laechelt-300x260@2x.jpg 600w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<div class=\"content\">\r\n\t\t\t<h2>Unsere Seminarempfehlung<\/h2>\r\n\t\t\t<p class=\"h3\">Das moderne Office-Management<\/p>\r\n\t\t\t<p>Entlaste deine Vorgesetzten wirkungsvoll \u2013 mit ganzheitlichem Denken, effizienter Organisation und klarer Kommunikation. Mit dem richtigen Know-how unterst\u00fctzt du deine F\u00fchrungskraft noch professioneller und wirst zur unverzichtbaren Top-Assistenz im Office.<\/p>\n<br\/>\r\n\t\t\t<a class=\"btn\" href=\"https:\/\/www.haufe-akademie.de\/8167\" onclick=\"target_econda_article()\" data-track-style=\"clickbtn\" data-track-type=\"link\" data-track-action=\"recoprimary\" target=\"_blank\">Seminar: Das moderne Office-Management<\/a>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"clear\"><\/div>\r\n\t\r\n<\/div><h2>Welche Kompetenzen braucht eine Sekret\u00e4rin?<\/h2>\n<p>Die Arbeit im Sekretariat verlangt nicht nur ein <strong>ausgepr\u00e4gtes Organisations- und Kommunikationstalent<\/strong>, sondern auch zahlreiche Kompetenzen in verschiedensten Bereichen. Die Sekretariat-Aufgaben sind vielf\u00e4ltig und h\u00e4ufig kommen mehrere Aufgaben auf einmal herein. Hier gilt es, den \u00dcberblick zu bewahren, sich <a href=\"https:\/\/www.haufe-akademie.de\/4147\">clever selbst zu organisieren<\/a> und <strong>Priorit\u00e4ten zu setzen<\/strong>.<\/p>\n<p>Je nach Unternehmen variieren die Aufgabenbereiche. Daher sehen die Anforderungen in den Stellenbeschreibungen f\u00fcr Sekret\u00e4rinnen nicht immer gleich aus. Folgende <strong>Hard- und Soft Skills sind allerdings fast immer gefordert<\/strong>, um die <a href=\"https:\/\/www.haufe-akademie.de\/3570\">F\u00fchrungsetage tatkr\u00e4ftig zu unterst\u00fctzen<\/a> und zu entlasten:<\/p>\n<h3>Hard Skills<\/h3>\n<p>Diese Hard Skills geh\u00f6ren (nat\u00fcrlich mit Ausnahmen) zum Grundlagen-Repertoire einer Sekret\u00e4rin und kommen im Bewerbungs-Portfolio immer gut an:<\/p>\n<ul>\n<li>Softwarekenntnisse: <a href=\"https:\/\/www.haufe-akademie.de\/30127\">Microsoft Office<\/a> wie <a href=\"https:\/\/www.haufe-akademie.de\/30138\">Excel<\/a> und <a href=\"https:\/\/www.haufe-akademie.de\/5549\">Powerpoint<\/a><\/li>\n<li>Sprachkenntnisse: Deutsch, <a href=\"https:\/\/www.haufe-akademie.de\/7885\">Englisch<\/a>, Franz\u00f6sisch \u2013 je nach internationaler Vernetztheit sind weitere Sprachkenntnisse von Vorteil<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/31576\">Datenschutzkenntnisse<\/a><\/li>\n<li>Branchenkenntnisse<\/li>\n<\/ul>\n<h3>Soft Skills<\/h3>\n<p>Die Hard Skills sind eine gute Basis f\u00fcr den Beruf oder die Weiterbildung als Sekret\u00e4rin. Was allerdings ebenso wichtig ist, sind Soft Skills, die im Alltag st\u00e4ndig gebraucht werden und <strong>zum t\u00e4glichen Erfolg verhelfen<\/strong>:<\/p>\n<ul>\n<li>Flexibilit\u00e4t<\/li>\n<li>Organisationsst\u00e4rke<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/7954\">diplomatischer Umgang<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/7498\">Teamf\u00e4higkeit<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8182\">Kommunikationsf\u00e4higkeit<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/7638\">Selbstreflexion<\/a><\/li>\n<li>Einf\u00fchlungsverm\u00f6gen<\/li>\n<li>vorausblickendes Denken<\/li>\n<li>Geduld<\/li>\n<li>Zeitmanagement<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8229\">Kritik- und Belastungsf\u00e4higkeit<\/a><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21621 size-full\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung.jpg\" alt=\"\" width=\"800\" height=\"384\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung.jpg 800w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung-150x72@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung-150x72.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung-702x336.jpg 702w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt-auflockerung-300x144@2x.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h2>Sekret\u00e4rin: Ausbildung &amp; Weiterbildung<\/h2>\n<p>Die Sekret\u00e4r-Ausbildung unterliegt keinem einheitlichen Plan und erfolgt meist durch <strong>Quer- oder Wiedereinsteiger<\/strong>. Trotzdem ist es wichtig, \u00fcber die notwendigen Kenntnisse zu verf\u00fcgen. Diese kann man sich allerdings <strong>\u00fcber verschiedene Ausbildungen und Kurse<\/strong> aneignen.<\/p>\n<h3>Chefsekret\u00e4rin: Ausbildung<\/h3>\n<p>Um eine Ausbildung zur Sekret\u00e4rin erfolgreich abschlie\u00dfen zu k\u00f6nnen, bieten sich verschiedene M\u00f6glichkeiten an. Zum einen ist es m\u00f6glich, eine <strong>Ausbildung als Kauffrau f\u00fcr B\u00fcrokommunikation<\/strong> oder B\u00fcromanagement zu machen. Mit diesen Kenntnissen in der Tasche hat man auf dem Arbeitsmarkt gute Chancen, denn diese F\u00e4higkeiten sind \u00fcberall gefragt.<\/p>\n<p>Zum anderen ist es auch sinnvoll, verschiedene <strong>Assistenz-Kurse zu belegen<\/strong>, wie beispielsweise:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/9278\">B\u00fcromanagement<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/7637\">Event-Management<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8157\">gepr\u00fcfte Office-Managerin<\/a><\/li>\n<\/ul>\n<h3>Sekret\u00e4rin: Weiterbildung<\/h3>\n<p>Gerade im Beruf der Sekret\u00e4rin ist <strong>regelm\u00e4\u00dfige Weiterbildung sinnvoll<\/strong>. Denn je nach Branche und Unternehmen sind andere Kenntnisse erforderlich. Verschiedene neue F\u00fchrungsans\u00e4tze und Verwaltungskonzepte verlangen au\u00dferdem Flexibilit\u00e4t. Deshalb ist es wichtig, \u00fcber die Basics zu verf\u00fcgen, die man in jeder Position als Sekret\u00e4rin braucht und sich dar\u00fcber hinaus auch <strong>andere Kompetenzen anzueignen<\/strong>, die in der angestrebten Position erforderlich sind.<\/p>\n<p>Hierf\u00fcr gibt es <strong>zahlreiche Lehrg\u00e4nge und Weiterbildungen<\/strong> in den folgenden Bereichen:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/34013\">Office-Management 4.0<\/a> \u2013 digital, hybrid, genial<\/li>\n<li>Erweiterte Management-F\u00e4higkeiten<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/30372\">Agiles Office-Management<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/8356\">Professionelle Korrespondenz<\/a> mit E-Mail und Brief<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/7498\">Doppelsekretariat<\/a> managen<\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/hierarchy\/kommunikation+und+gespraechsfuehrung\">Professionelle Gespr\u00e4chsf\u00fchrung<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/5655\">Weiterbildung Sekretariatsassistenz<\/a><\/li>\n<li><a href=\"https:\/\/www.haufe-akademie.de\/30305?slt=true\">Management-Assistenz Fernkurs<\/a><\/li>\n<\/ul>\n<h2>Wie viel verdient man als Sekret\u00e4rin?<\/h2>\n<p>Bei einer Sekret\u00e4rin, auch Office Managerin oder F\u00fchrungsassistenz <strong>variiert das Gehalt <\/strong>je nach Firma, Aufgabenbereichen und Qualifikationen.<\/p>\n<p>Im Monat verdient eine Sekret\u00e4rin <strong>als Neueinsteigerin im Schnitt ca. 2.000 Euro<\/strong>, steigt die Berufserfahrung auf f\u00fcnf bis zehn Jahre, eher um die 2.400 Euro. Das Gehalt kann danach weiter steigen und je nach Firma und Verantwortungsbereich <strong>im besten Fall sogar rund 4.000 Euro<\/strong> im Monat betragen. Im Jahr variiert das Sekret\u00e4rinnen-Gehalt also von 27.000 Euro bis 46.000 Euro brutto.<\/p>\n<div class=\"seminartipp\">\r\n\t\r\n\t<div class=\"content-wrapper\">\r\n\t\t\r\n\t\t\t<div class=\"image\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"73\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/seminartipp-sekretaerin.jpg\" class=\"attachment-pod size-pod\" alt=\"\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/seminartipp-sekretaerin.jpg 230w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/seminartipp-sekretaerin-150x72.jpg 150w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<div class=\"content\">\r\n\t\t\t<h2>Unsere Empfehlung<\/h2>\r\n\t\t\t<p class=\"h3\">Professionelle Assistenz f\u00fcr Quer- und Wiedereinsteiger:innen<\/p>\r\n\t\t\t<p>Nutzen Sie das ideale Check-up-Training f\u00fcr Quer- und Wiedereinsteiger in der Assistenz \u2013 Sie \u00fcberpr\u00fcfen Ihre Arbeitsweise, Organisation und Methoden, optimieren diese an den richtigen Stellen und bringen sie auf den aktuellen Stand. Sie reflektieren Ihr Gespr\u00e4chsverhalten und erhalten wertvolle Tipps zur professionellen Kommunikation in der Assistenz. Au\u00dferdem lernen Sie Routineabl\u00e4ufe zu standardisieren und Ihr Aufgabengebiet eigenverantwortlich zu gestalten.<\/p>\n<br\/>\r\n\t\t\t<a class=\"btn\" href=\"https:\/\/www.haufe-akademie.de\/8761\" onclick=\"target_econda_article()\" data-track-style=\"clickbtn\" data-track-type=\"link\" data-track-action=\"recoprimary\" target=\"_blank\">Seminar: Professionelle Assistenz f\u00fcr Quer- und Wiedereinsteiger:innen<\/a>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"clear\"><\/div>\r\n\t\r\n<\/div><h2>Wie wird man Sekret\u00e4rin?<\/h2>\n<p>Dass es keine direkte Ausbildung zur Sekret\u00e4rin gibt, hat den Vorteil, dass auch die Sekret\u00e4rin-Jobbeschreibungen <strong>unterschiedliche Anforderungen<\/strong> beinhalten. Das bedeutet auch, dass sich zahlreiche Ausbildungen als Referenz eignen und Bewerber f\u00fcr den Beruf als Sekret\u00e4rin qualifizieren.<\/p>\n<blockquote><p><strong>Der Sekretariatsberuf im Wandel <\/strong><\/p>\n<p><a href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/167555\/umfrage\/frauenanteil-in-verschiedenen-berufsgruppen-in-deutschland\/\">Heute wendet sich die Position des Sekretariats \u2013 oder besser: Office-Managements \u2013 sowohl an M\u00e4nner als auch Frauen, obwohl die Frauen in Unternehmensf\u00fchrung- und Organisation mit \u00fcber 60 % noch deutlich in der Mehrzahl sind<\/a>. Zus\u00e4tzlich \u00e4ndern sich die Anforderungen an diesen Beruf durch die zunehmende Digitalisierung und neue Management-Konzepte stetig.<\/p><\/blockquote>\n<h2>Sekret\u00e4rin: Arbeitspl\u00e4tze der Zukunft \u2013 Haufe Akademie<\/h2>\n<p>Als Sekret\u00e4rin ist man <strong>Schnittstelle und Kernpunkt eines Unternehmens<\/strong>. Sie verbindet alle Akteure und ist oft gleichzeitig die \u201eVisitenkarte\u201c, die Kunden als Erstes kennenlernen. Zudem ist sie wertvolle Unterst\u00fctzung f\u00fcr die F\u00fchrungsetage und \u00fcbernimmt kleine bis gro\u00dfe T\u00e4tigkeiten, die ein <strong>breites Spektrum an Hard- und Soft Skills <\/strong>voraussetzen. Damit hat die Sekret\u00e4rin eine verantwortungsvolle Position inne.<\/p>\n<p>Wollen auch Sie mehr Verantwortung \u00fcbertragen bekommen, <strong>neue F\u00e4higkeiten im Zuge des <\/strong><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalentwicklung\/digitaler-wandel-die-antwort-der-personalentwicklung\/\"><strong>digitalen Wandels<\/strong><\/a><strong> entwickeln<\/strong> und unverzichtbares Element in einem Unternehmen sein, dann sind Sie bei unseren Seminaren richtig.<\/p>\n<div>\n<hr \/>\n<p><em>Aus\u00a0Gr\u00fcnden\u00a0der besseren\u00a0Lesbarkeit\u00a0wird im Beitrag auf die gleichzeitige Verwendung weiblicher und m\u00e4nnlicher Sprachformen verzichtet und das generische Maskulinum verwendet. S\u00e4mtliche Personenbezeichnungen gelten gleicherma\u00dfen f\u00fcr alle Geschlechter.<\/em><\/p>\n<\/div>\n<h2>FAQs: \u201eSekret\u00e4rin\u201c<\/h2>\n<h3>Was macht man als Sekret\u00e4rin?<\/h3>\n<p>Als Sekret\u00e4rin ist man <strong>Schnittstelle zwischen allen Beteiligten in einem Unternehmen<\/strong> und h\u00e4ufig erste Kontaktperson. Sie unterst\u00fctzt die F\u00fchrungsetage mit kleinen, aber auch gro\u00dfen und verantwortungsvollen Aufgaben. Sie verwaltet und organisiert Termine und <strong>erledigt administrative Aufgaben<\/strong>.<\/p>\n<h3>Wie sagt man heute zur Sekret\u00e4rin?<\/h3>\n<p>Heute gibt es viele Bezeichnungen f\u00fcr eine Sekret\u00e4rin, da der Aufgabenbereich nicht mehr wie fr\u00fcher klar definiert ist. Begriffe wie <strong>Office Manager, Assistenz der Gesch\u00e4ftsf\u00fchrung oder B\u00fcrokaufmann<\/strong> k\u00f6nnen alle das Berufsbild der Sekret\u00e4rin beinhalten.<\/p>\n<h3>Was f\u00fcr einen Abschluss braucht man als Sekret\u00e4rin?<\/h3>\n<p>Da die Aufgabenbereiche heute nicht mehr klar definiert sind, gibt es die eine passende Ausbildung zur Sekret\u00e4rin nicht. Vielmehr gibt es <strong>verschiedene Ausbildungen<\/strong>, die f\u00fcr diesen Beruf qualifizieren k\u00f6nnen. Zu empfehlen ist eine Ausbildung als B\u00fcrokaufmann oder B\u00fcrokauffrau oder eine Weiterbildung in Office-Management.<\/p>\n<h3>Was verdient eine Sekret\u00e4rin?<\/h3>\n<p>Eine Sekret\u00e4rin hat h\u00e4ufig ein <strong>Startgehalt von ca. 27.000 Euro im Jahr<\/strong>, kann aber je nach Unternehmen, Berufserfahrung und Verantwortungsbereich bis zu 46.000 Euro oder weit dar\u00fcber verdienen.<\/p>\n<div class=\"seminartipp\">\r\n\t\r\n\t<div class=\"content-wrapper\">\r\n\t\t\r\n\t\t\t<div class=\"image\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"143\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/10\/business-Coaching_620x580.jpg\" class=\"attachment-pod size-pod\" alt=\"\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/10\/business-Coaching_620x580.jpg 620w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/10\/business-Coaching_620x580-150x140@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/10\/business-Coaching_620x580-150x140.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/10\/business-Coaching_620x580-300x281@2x.jpg 600w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<div class=\"content\">\r\n\t\t\t<h2>Unsere Empfehlung<\/h2>\r\n\t\t\t<p class=\"h3\">Berufliche Neuorientierung? Business Coaching unterst\u00fctzt dich dabei!<\/p>\r\n\t\t\t<p>Wenn du dich beruflich neu orientieren m\u00f6chtest und eine klare Richtung suchst, ist Business Coaching die ideale Begleitung. Ein:e erfahrene:r Coach:in unterst\u00fctzt dich dabei, deine St\u00e4rken, Ziele und Potenziale zu erkennen, damit du den n\u00e4chsten Karriereschritt sicher und zielgerichtet gehen kannst \u2013 sei es in einem neuen Berufsfeld oder auf deinem aktuellen Weg. <\/p>\n<br\/>\r\n\t\t\t<a class=\"btn\" href=\"https:\/\/www.haufe-akademie.de\/coaching\" onclick=\"target_econda_article()\" data-track-style=\"clickbtn\" data-track-type=\"link\" data-track-action=\"recoprimary\" target=\"_blank\">Jetzt Coaching-Angebote entdecken<\/a>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"clear\"><\/div>\r\n\t\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Eine Sekret\u00e4rin \u00fcbernimmt administrative Aufgaben im Sekretariat, f\u00fchrt das Front-Office, regelt Telefon- und E-Mail-Verkehr und verwaltet Termine. Heute kann es unter Umst\u00e4nden auch sein, dass eine Sekret\u00e4rin andere Mitarbeiter brieft und Pr\u00e4sentations- oder sogar F\u00fchrungsaufgaben \u00fcbernimmt. Sekret\u00e4rin: Key Facts Ausbildung Kauffrau f\u00fcr B\u00fcrokommunikation B\u00fcromanagement gepr\u00fcfte Office-Managerin Hard Skills EDV-Kenntnisse, Microsoft Office Sprachenkenntnisse Branchenkenntnisse Weiterbildung Office-Management<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":30,"featured_media":21619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"yes","_lmt_disable":"no","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[95,1786],"tags":[3916,1752,560,2240,3915,3909,1144,3914,3913,3917,2159,2161,2160,3918,210],"class_list":{"0":"post-21599","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-assistenz-und-office-management","8":"category-berufe","9":"tag-chef-sekretaerin","10":"tag-assistenz-der-geschaeftsfuehrung","11":"tag-aufgaben","12":"tag-ausbildung","13":"tag-executive-assistant","14":"tag-gehalt","15":"tag-kompetenzen","16":"tag-management-assistant","17":"tag-office-managerin","18":"tag-persoenliche-assistenz","19":"tag-sekretaer","20":"tag-sekretariat","21":"tag-sekretaerin","22":"tag-vorstandsassistenz","23":"tag-weiterbildung"},"acf":{"p_authors":[5612]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sekret\u00e4rin: Definition, Aufgaben &amp; Gehalt<\/title>\n<meta name=\"description\" content=\"Alles Wissenswerte zum Beruf Sekret\u00e4rin \u2713 Gehalt \u2713 Aufgaben \u2713 Hard- und Soft Skills \u2713 Aus- und Weiterbildungen \u25b6 mehr erfahren\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sekret\u00e4rin: Definition, Aufgaben &amp; Gehalt\" \/>\n<meta property=\"og:description\" content=\"Alles Wissenswerte zum Beruf Sekret\u00e4rin \u2713 Gehalt \u2713 Aufgaben \u2713 Hard- und Soft Skills \u2713 Aus- und Weiterbildungen \u25b6 mehr erfahren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T07:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T11:32:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Online-Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Online-Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sekret\u00e4rin: Definition, Aufgaben & Gehalt","description":"Alles Wissenswerte zum Beruf Sekret\u00e4rin \u2713 Gehalt \u2713 Aufgaben \u2713 Hard- und Soft Skills \u2713 Aus- und Weiterbildungen \u25b6 mehr erfahren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/","og_locale":"de_DE","og_type":"article","og_title":"Sekret\u00e4rin: Definition, Aufgaben & Gehalt","og_description":"Alles Wissenswerte zum Beruf Sekret\u00e4rin \u2713 Gehalt \u2713 Aufgaben \u2713 Hard- und Soft Skills \u2713 Aus- und Weiterbildungen \u25b6 mehr erfahren","og_url":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2022-10-19T07:00:37+00:00","article_modified_time":"2025-09-30T11:32:08+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","type":"image\/jpeg"}],"author":"Online-Redaktion","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Online-Redaktion","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/"},"author":{"name":"Angelika Joubert","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63"},"headline":"Sekret\u00e4rin: Aufgaben, Weiterbildungen &#038; Gehalt","datePublished":"2022-10-19T07:00:37+00:00","dateModified":"2025-09-30T11:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/"},"wordCount":1524,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","keywords":["(Chef-)Sekret\u00e4rin","Assistenz der Gesch\u00e4ftsf\u00fchrung","Aufgaben","ausbildung","Executive Assistant","Gehalt","Kompetenzen","Management Assistant","Office Managerin","pers\u00f6nliche Assistenz","Sekret\u00e4r","sekretariat","Sekret\u00e4rin","Vorstandsassistenz","Weiterbildung"],"articleSection":["Assistenz und Office-Management","Berufe"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/","url":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/","name":"Sekret\u00e4rin: Definition, Aufgaben & Gehalt","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","datePublished":"2022-10-19T07:00:37+00:00","dateModified":"2025-09-30T11:32:08+00:00","description":"Alles Wissenswerte zum Beruf Sekret\u00e4rin \u2713 Gehalt \u2713 Aufgaben \u2713 Hard- und Soft Skills \u2713 Aus- und Weiterbildungen \u25b6 mehr erfahren","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","width":800,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/sekretaer-sekretaerin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Berufe","item":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/"},{"@type":"ListItem","position":3,"name":"Sekret\u00e4rin: Aufgaben, Weiterbildungen &#038; Gehalt"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63","name":"Angelika Joubert","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","caption":"Angelika Joubert"},"url":"https:\/\/www.haufe-akademie.de\/blog\/author\/angelika-joubert\/"}]}},"modified_by":"Helena T\u00f6mke","jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/10\/sekretaerin-aufgaben-weiterbildungen-gehalt.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/21599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=21599"}],"version-history":[{"count":6,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/21599\/revisions"}],"predecessor-version":[{"id":45284,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/21599\/revisions\/45284"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/5612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/21619"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=21599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=21599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=21599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}